{"id":9,"date":"2025-11-04T04:38:51","date_gmt":"2025-11-04T04:38:51","guid":{"rendered":"https:\/\/techapps.ovh\/?p=9"},"modified":"2026-02-06T03:40:51","modified_gmt":"2026-02-06T03:40:51","slug":"9","status":"publish","type":"post","link":"https:\/\/techapps.ovh\/index.php\/2025\/11\/04\/9\/","title":{"rendered":"POL\u00cdTICA DE PRIVACIDAD"},"content":{"rendered":"\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h.al31zweevwsc_l\">POL\u00cdTICA DE PRIVACIDAD<\/h1>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h.al31zweevwsc_l\">Fecha de la \u00faltima revisi\u00f3n:&nbsp;22 de Octubre de 2025La presente Pol\u00edtica de Privacidad describe c\u00f3mo Techapps]&nbsp;recopila, utiliza y protege la informaci\u00f3n personal que usted proporciona o que se recopila autom\u00e1ticamente cuando utiliza nuestra aplicaci\u00f3n m\u00f3vil&nbsp;PomodoroFLotime&nbsp;(en adelante, \u00abla Aplicaci\u00f3n\u00bb).<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.gydy35uhllw_l\">0. IDENTIDAD Y DATOS DEL RESPONSABLE DEL TRATAMIENTO<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">El responsable del tratamiento de sus datos personales es:Identidad:&nbsp;Yone Dieppa MedinaDirecci\u00f3n:Farmaceutico Padilla.N8,7D,Gran Canaria, Espa\u00f1aCorreo electr\u00f3nico de contacto:&nbsp;techapps2010@proton.me&nbsp;<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h.yi0wuz7zvzst_l\">1. DATOS PERSONALES QUE RECOPILAMOS Y TRATAMOS<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Nuestra Aplicaci\u00f3n ha sido dise\u00f1ada para no recopilar datos sensibles (como datos de salud, origen racial o \u00e9tnico, opiniones pol\u00edticas, etc.) ni solicitar directamente datos de registro de usuario (nombre, correo electr\u00f3nico). Sin embargo, para mostrar publicidad relevante a trav\u00e9s de AdMob, la Aplicaci\u00f3n trata las siguientes categor\u00edas de informaci\u00f3n:1.1 Datos Recopilados Autom\u00e1ticamente por la Aplicaci\u00f3n (AdMob)Estos datos son generados por su dispositivo y se utilizan \u00fanicamente para el funcionamiento b\u00e1sico, la seguridad y la medici\u00f3n de la interacci\u00f3n con la publicidad de AdMob. Identificadores \u00danicos del Dispositivo: Identificador de Publicidad de Google (GAID en Android) o IDFA (en iOS)&#8230; Datos de Uso y Dispositivo: Direcci\u00f3n IP, Tipo de dispositivo, etc&#8230;1.2 Datos Generados y Almacenados Localmente (StatsManager)La Aplicaci\u00f3n genera y almacena la siguiente informaci\u00f3n relativa a la productividad y el uso de la t\u00e9cnica Pomodoro. Estos datos se guardan&nbsp;\u00daNICAMENTE en la memoria local del dispositivo del usuario y NUNCA son enviados a un servidor externo ni son compartidos con terceros.&nbsp;Datos de Estad\u00edsticas de Estudio (StatsManager): Tiempos de enfoque completados, tiempos de descanso registrados, n\u00famero de ciclos Pomodoro completados y fechas de uso de la funci\u00f3n.1.3 Datos no TratadosNo recopilamos ni tratamos su nombre, direcci\u00f3n de correo electr\u00f3nico, n\u00fameros de tel\u00e9fono ni datos de pago&#8230;<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.rn6zp1i1asng_l\">2. FINALIDAD DEL TRATAMIENTO DE LA INFORMACI\u00d3N<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">La finalidad principal y \u00fanica del tratamiento de los datos mencionados en el punto 1.1 y 1.2 es:&nbsp;Finalidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Descripci\u00f3n DetalladaPublicidad Personalizada (AdMob)&nbsp;&nbsp; &nbsp; &nbsp; Utilizar los identificadores de dispositivo y datos de geolocalizaci\u00f3n aproximada para mostrar anuncios que se ajusten a sus intereses y perfil, gestionar las impresiones de anuncios y realizar la facturaci\u00f3n a los anunciantes.Medici\u00f3n y An\u00e1lisis&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Evaluar la efectividad de las campa\u00f1as publicitarias y realizar an\u00e1lisis internos sobre el uso de la Aplicaci\u00f3n para detectar errores y mejorar el rendimiento t\u00e9cnico.Seguridad y Prevenci\u00f3n del Fraude&nbsp; &nbsp; &nbsp; Monitorear el tr\u00e1fico de la red para detectar actividades fraudulentas relacionadas con la publicidad (ej. clics no v\u00e1lidos) y proteger los derechos de la Empresa y Google.Mostrar Estad\u00edsticas Locales&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp;&nbsp;Utilizar los datos de StatsManager para calcular y mostrar al usuario su progreso y rendimiento dentro de la Aplicaci\u00f3n (funci\u00f3n principal).&nbsp;<br><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.sarjjxaq87av_l\">3. BASE LEGAL PARA EL TRATAMIENTO (RGPD)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Seg\u00fan lo estipulado en el Art\u00edculo 6 del RGPD, solo procesamos sus datos personales si contamos con una base legal v\u00e1lida.Para el uso de Identificadores y datos de seguimiento (Publicidad Personalizada):Base Legal:&nbsp;Consentimiento Expl\u00edcito (Art. 6.1.a RGPD).Detalle:&nbsp;El seguimiento de su actividad y el uso de identificadores \u00fanicos para la personalizaci\u00f3n de anuncios se realiza&nbsp;\u00fanicamente si usted otorga su consentimiento&nbsp;a trav\u00e9s del&nbsp;Mecanismo de Gesti\u00f3n de Consentimiento (CMP)&nbsp;que se le presenta al iniciar la Aplicaci\u00f3n. Usted puede revocar este consentimiento en cualquier momento.Para el tratamiento de datos para Seguridad y Cumplimiento Legal:Base Legal:&nbsp;Inter\u00e9s Leg\u00edtimo (Art. 6.1.f RGPD)&nbsp;y&nbsp;Obligaci\u00f3n Legal (Art. 6.1.c RGPD).Detalle:&nbsp;El tratamiento es necesario para mantener la seguridad de la red y cumplir con las normativas contra el fraude.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.4ilp7vg8aghv_l\">4. DESTINATARIOS DE LOS DATOS Y TERCEROS<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Compartimos sus datos con los siguientes terceros, que act\u00faan como&nbsp;Encargados del Tratamiento&nbsp;o&nbsp;Responsables Conjuntos&nbsp;(en el caso de Google para AdMob).<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h.cq25vgobjm2h_l\">4.1 Google (AdMob y Servicios de Publicidad)<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Servicio:&nbsp;AdMob (Plataforma de Publicidad de Google).Datos Compartidos:&nbsp;Identificador de Publicidad (GAID\/IDFA), direcci\u00f3n IP, datos del dispositivo, datos de interacci\u00f3n con los anuncios.Finalidad:&nbsp;Mostrar publicidad personalizada y no personalizada.Pol\u00edtica de Privacidad de Google:&nbsp;Puede consultar los detalles sobre c\u00f3mo Google utiliza estos datos en su propia pol\u00edtica de privacidad:&nbsp;https:\/\/policies.google.com\/privacy&nbsp;y, espec\u00edficamente para AdMob, en:&nbsp;https:\/\/policies.google.com\/technologies\/partner-sites<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.8j0ah38lszpn_l\">5. TRANSFERENCIAS INTERNACIONALES DE DATOS<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Dado que utilizamos los servicios de Google (AdMob), la informaci\u00f3n recopilada se transfiere y almacena en servidores ubicados en los&nbsp;Estados Unidos de Am\u00e9rica (EE. UU.)&nbsp;y potencialmente en otras ubicaciones internacionales.El Responsable garantiza que estas transferencias se realizan con las salvaguardas adecuadas, conforme al Art\u00edculo 46 del RGPD:Marco de Privacidad de Datos UE-EE. UU. (DPF):&nbsp;Google ha certificado su adhesi\u00f3n al Marco de Privacidad de Datos UE-EE. UU.Cl\u00e1usulas Contractuales Tipo (CCT):&nbsp;En caso de que el DPF no sea aplicable o suficiente, utilizamos las Cl\u00e1usulas Contractuales Tipo aprobadas por la Comisi\u00f3n Europea, que garantizan un nivel de protecci\u00f3n sustancialmente equivalente al exigido por el RGPD.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.zckscv6ioxu6_l\">6. PERIODO DE CONSERVACI\u00d3N DE LOS DATOS<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Conservaremos sus datos personales solo durante el tiempo necesario para cumplir con los fines descritos en esta pol\u00edtica o hasta que revoque su consentimiento para el procesamiento con fines publicitarios.Datos de Publicidad (AdMob):&nbsp;Se conservan hasta&nbsp;13 meses&nbsp;desde la \u00faltima interacci\u00f3n, de acuerdo con las pol\u00edticas de retenci\u00f3n de Google para datos de anal\u00edtica y publicidad.&nbsp;<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.68azxy1iol6d_l\">7. SUS DERECHOS DE PRIVACIDAD (RGPD Y LOPDGDD)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Usted tiene una serie de derechos irrenunciables en relaci\u00f3n con el tratamiento de sus datos personales. Para ejercer cualquiera de ellos, puede contactarnos a trav\u00e9s de los datos de contacto proporcionados en el punto 0.Importante:&nbsp;Dado que la mayor parte de los datos personales (Identificadores y IP) son procesados por Google a trav\u00e9s de AdMob, al ejercer sus derechos (como Acceso o Supresi\u00f3n), actuaremos como su punto de contacto inicial para&nbsp;facilitar la gesti\u00f3n de su solicitud ante Google, de acuerdo con las condiciones de Responsable Conjunto.Usted tiene derecho a:Derecho de Acceso:&nbsp;Saber si estamos tratando sus datos y obtener una copia de ellos (gestionada directamente o en coordinaci\u00f3n con Google).Derecho de Rectificaci\u00f3n:&nbsp;Solicitar la modificaci\u00f3n de datos inexactos o incompletos.Derecho de Supresi\u00f3n (Derecho al Olvido):&nbsp;Solicitar la eliminaci\u00f3n de sus datos cuando ya no sean necesarios para los fines que fueron recogidos.Derecho de Oposici\u00f3n:&nbsp;Oponerse al tratamiento de sus datos por motivos relacionados con su situaci\u00f3n particular, incluido el&nbsp;profiling&nbsp;publicitario.Derecho a la Portabilidad:&nbsp;Recibir sus datos en un formato estructurado y de uso com\u00fan y transmitirlos a otro responsable (solo aplicable a datos tratados por consentimiento o por contrato).Derecho a la Limitaci\u00f3n del Tratamiento:&nbsp;Solicitar la suspensi\u00f3n temporal del tratamiento en ciertos supuestos (ej. impugnaci\u00f3n de la exactitud de los datos).Derecho a Retirar el Consentimiento:&nbsp;Retirar en cualquier momento el consentimiento que haya otorgado para el tratamiento de sus datos con fines publicitarios.Si considera que hemos infringido sus derechos o no hemos atendido su solicitud, tiene derecho a presentar una reclamaci\u00f3n ante la Autoridad de Control competente (en Espa\u00f1a, la&nbsp;Agencia Espa\u00f1ola de Protecci\u00f3n de Datos &#8211; AEPD).<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.bff1f551q3nn_l\">8. PRIVACIDAD DE MENORES DE EDAD<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Nuestra Aplicaci\u00f3n est\u00e1 destinada al p\u00fablico general. No recopilamos conscientemente datos personales de menores de&nbsp;16 a\u00f1os&nbsp;en la Uni\u00f3n Europea sin el consentimiento de un progenitor o tutor. Si un padre o tutor descubre que su hijo nos ha proporcionado datos sin su consentimiento, debe contactarnos.&nbsp;<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.r3ceiupzyvkv_l\">9. MEDIDAS DE SEGURIDAD<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Hemos implementado medidas de seguridad t\u00e9cnicas y organizativas adecuadas para proteger sus datos personales contra el acceso no autorizado, la divulgaci\u00f3n, la alteraci\u00f3n o la destrucci\u00f3n.&nbsp;Nuestra principal medida de seguridad es la minimizaci\u00f3n de datos: la Aplicaci\u00f3n no almacena Identificadores de Publicidad ni ninguna otra informaci\u00f3n personal en servidores propios.En cuanto a los datos de StatsManager, estos se almacenan&nbsp;\u00fanicamente en el dispositivo del usuario&nbsp;y est\u00e1n sujetos a las protecciones del sistema operativo. La&nbsp;no-transmisi\u00f3n&nbsp;de estos datos es la m\u00e1xima garant\u00eda de seguridad.La transmisi\u00f3n de los datos del dispositivo a terceros (AdMob) se realiza utilizando conexiones cifradas (HTTPS) para garantizar su protecci\u00f3n en tr\u00e1nsito. No obstante, reconocemos que ninguna transmisi\u00f3n de datos por Internet es 100% segura.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.kd87a17gfnru_l\">10. CAMBIOS A ESTA POL\u00cdTICA DE PRIVACIDAD<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Podemos actualizar esta Pol\u00edtica de Privacidad peri\u00f3dicamente. Si realizamos cambios significativos, se lo notificaremos mediante una notificaci\u00f3n dentro de la Aplicaci\u00f3n o a trav\u00e9s de otros medios antes de que los cambios entren en vigor. Le recomendamos revisar esta pol\u00edtica de forma regular.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.vflaie1gtom3_l\">11. INFORMACI\u00d3N DE CONTACTO<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Si tiene preguntas, comentarios o desea ejercer sus derechos de privacidad, puede contactar al Responsable del Tratamiento:Correo electr\u00f3nico (preferido):&nbsp;techapps2010@proton.meDirecci\u00f3n Postal:Farmaceutico Padilla.35012,N8,7D,Gran Canaria, Espa\u00f1a<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.h4xqhetinv1f_l\">12. DERECHOS DE PRIVACIDAD DE LOS RESIDENTES EN CALIFORNIA (CCPA\/CPRA)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Si usted es residente de California, esta secci\u00f3n se aplica a usted y le confiere derechos espec\u00edficos con respecto al tratamiento de sus datos personales bajo la Ley de Privacidad del Consumidor de California (CCPA), enmendada por la Ley de Derechos de Privacidad de California (CPRA).<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h.bob008s18ugy_l\">12.1 Categor\u00edas de Informaci\u00f3n Personal Compartida (Venta\/Compartici\u00f3n)<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">En los 12 meses anteriores a la fecha de vigencia de esta Pol\u00edtica, hemos compartido las siguientes categor\u00edas de informaci\u00f3n personal con fines de publicidad dirigida (lo que CCPA\/CPRA define como \u00abventa\u00bb o \u00abintercambio\u00bb de datos):Identificadores:&nbsp;Identificadores \u00fanicos del dispositivo, Direcci\u00f3n IP.Informaci\u00f3n de Actividad de Internet o Red:&nbsp;Informaci\u00f3n sobre su interacci\u00f3n con nuestra Aplicaci\u00f3n y los anuncios.Datos de Geolocalizaci\u00f3n Aproximada:&nbsp;Inferidos a partir de la Direcci\u00f3n IP.El destinatario de esta informaci\u00f3n es&nbsp;Google (AdMob), con el \u00fanico fin de mostrar publicidad personalizada.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h.aoi4kni9fdjr_l\">12.2 Derecho a No Vender o Compartir Informaci\u00f3n Personal (Right to Opt-Out)<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Usted tiene el derecho de&nbsp;oponerse a la venta o el intercambio&nbsp;de su informaci\u00f3n personal con terceros para fines de publicidad dirigida.Mecanismo de Exclusi\u00f3n (Opt-Out):&nbsp;Dado que nuestra Aplicaci\u00f3n utiliza un Mecanismo de Gesti\u00f3n de Consentimiento (CMP), usted puede ejercer este derecho de la siguiente manera:Usuarios del EEE\/UK:&nbsp;Su consentimiento se rige por la Secci\u00f3n 3 (Consentimiento Expl\u00edcito). Si retira el consentimiento, no se compartir\u00e1 su informaci\u00f3n para publicidad personalizada.Todos los Usuarios (incluidos California):&nbsp;Usted debe&nbsp;desactivar la personalizaci\u00f3n de anuncios&nbsp;en la configuraci\u00f3n de privacidad de su dispositivo m\u00f3vil:Android:&nbsp;Configuraci\u00f3n &gt; Google &gt; Anuncios &gt; Restablecer ID de publicidad y\/o Desactivar la personalizaci\u00f3n de anuncios.iOS:&nbsp;Configuraci\u00f3n &gt; Privacidad &gt; Rastreo &gt; Limitar Rastreo de Anuncios (o desactivar el rastreo para la App).Para ejercer formalmente su derecho a optar por la exclusi\u00f3n (Opt-Out) o para solicitar un informe de sus datos, contacte con nosotros utilizando la informaci\u00f3n proporcionada en la Secci\u00f3n 11.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h.k87qbet41hx3_l\">12.3 Otros Derechos CCPA\/CPRA<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Los residentes de California tambi\u00e9n tienen derecho a:Derecho a Saber:&nbsp;Solicitar informaci\u00f3n espec\u00edfica sobre las categor\u00edas y las piezas concretas de datos personales que hemos recopilado sobre usted en los \u00faltimos 12 meses.Derecho de Supresi\u00f3n (Delete):&nbsp;Solicitar la eliminaci\u00f3n de la informaci\u00f3n personal que hemos recopilado sobre usted.Derecho a No Discriminaci\u00f3n:&nbsp;No recibir un trato discriminatorio por ejercer sus derechos de privacidad del CCPA\/CPRA.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h.uuu7rruf2bgp_l\">13. NOTA IMPORTANTE SOBRE ADMOB Y CONSENTIMIENTO<\/h2>\n\n\n\n<p>Para garantizar el cumplimiento del RGPD y de la Pol\u00edtica de Consentimiento de la UE de Google, usted&nbsp;DEBE&nbsp;implementar un&nbsp;Mecanismo de Gesti\u00f3n de Consentimiento (CMP)&nbsp;certificado por Google, como el de Funding Choices o un proveedor externo, antes de mostrar cualquier anuncio. Este mecanismo es el que le permitir\u00e1 obtener legalmente el consentimiento expl\u00edcito del usuario para el uso de identificadores y el seguimiento publicitario, tal como se establece en el punto 3 de esta pol\u00edtica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE PRIVACIDAD Fecha de la \u00faltima revisi\u00f3n:&nbsp;22 de Octubre de 2025La presente Pol\u00edtica de Privacidad describe c\u00f3mo Techapps]&nbsp;recopila, utiliza y protege la informaci\u00f3n personal que usted proporciona o que se recopila autom\u00e1ticamente cuando utiliza nuestra aplicaci\u00f3n m\u00f3vil&nbsp;PomodoroFLotime&nbsp;(en adelante, \u00abla Aplicaci\u00f3n\u00bb). 0. IDENTIDAD Y DATOS DEL RESPONSABLE DEL TRATAMIENTO El responsable del tratamiento de sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":2,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"predecessor-version":[{"id":20,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/posts\/9\/revisions\/20"}],"wp:attachment":[{"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/techapps.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}